{"id":28,"date":"2021-12-08T11:43:21","date_gmt":"2021-12-08T11:43:21","guid":{"rendered":"http:\/\/www.idzine4u.nl\/claustegelwerken\/?page_id=28"},"modified":"2021-12-08T11:52:53","modified_gmt":"2021-12-08T11:52:53","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-block\" id=\"wpforms-30\"><form id=\"wpforms-form-30\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"30\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/claustegelwerken\/wp-json\/wp\/v2\/pages\/28\" data-token=\"806df42ec0cd34cee33432b23f2781e4\" data-token-time=\"1778702955\"><noscript class=\"wpforms-error-noscript\">Schakel JavaScript in je browser in om dit formulier in te vullen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-30-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">Naam <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-30-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-30-field_0\" class=\"wpforms-field-sublabel after\">Voornaam<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-30-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-30-field_0-last\" class=\"wpforms-field-sublabel after\">Achternaam<\/label><\/div><\/div><\/div><div id=\"wpforms-30-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-30-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-30-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-30-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-30-field_3\">Telefoonnummer<\/label><input type=\"text\" id=\"wpforms-30-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" ><\/div><div id=\"wpforms-30-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-30-field_2\">Uw bericht <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-30-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"30\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/pages\/28\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-30\" class=\"wpforms-submit\" data-alt-text=\"Aan het versturen...\" data-submit-text=\"Verzenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Verzenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Bezig met laden\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-28","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - Claus Tegelwerken<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - Claus Tegelwerken\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Claus Tegelwerken\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-08T11:52:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/contact\\\/\",\"url\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/contact\\\/\",\"name\":\"Contact - Claus Tegelwerken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/#website\"},\"datePublished\":\"2021-12-08T11:43:21+00:00\",\"dateModified\":\"2021-12-08T11:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/#website\",\"url\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/\",\"name\":\"Claus Tegelwerken\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/#organization\",\"name\":\"Claus Tegelwerken\",\"url\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-Transparant-wit.png\",\"contentUrl\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-Transparant-wit.png\",\"width\":1308,\"height\":708,\"caption\":\"Claus Tegelwerken\"},\"image\":{\"@id\":\"https:\\\/\\\/www.idzine4u.nl\\\/claustegelwerken\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - Claus Tegelwerken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/","og_locale":"nl_NL","og_type":"article","og_title":"Contact - Claus Tegelwerken","og_url":"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/","og_site_name":"Claus Tegelwerken","article_modified_time":"2021-12-08T11:52:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/","url":"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/","name":"Contact - Claus Tegelwerken","isPartOf":{"@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/#website"},"datePublished":"2021-12-08T11:43:21+00:00","dateModified":"2021-12-08T11:52:53+00:00","breadcrumb":{"@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.idzine4u.nl\/claustegelwerken\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/#website","url":"https:\/\/www.idzine4u.nl\/claustegelwerken\/","name":"Claus Tegelwerken","description":"","publisher":{"@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.idzine4u.nl\/claustegelwerken\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/#organization","name":"Claus Tegelwerken","url":"https:\/\/www.idzine4u.nl\/claustegelwerken\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/#\/schema\/logo\/image\/","url":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-content\/uploads\/2021\/12\/cropped-Transparant-wit.png","contentUrl":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-content\/uploads\/2021\/12\/cropped-Transparant-wit.png","width":1308,"height":708,"caption":"Claus Tegelwerken"},"image":{"@id":"https:\/\/www.idzine4u.nl\/claustegelwerken\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/pages\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":2,"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/pages\/28\/revisions"}],"predecessor-version":[{"id":31,"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/pages\/28\/revisions\/31"}],"wp:attachment":[{"href":"https:\/\/www.idzine4u.nl\/claustegelwerken\/wp-json\/wp\/v2\/media?parent=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}